{"id":9719,"date":"2011-08-01T07:41:57","date_gmt":"2011-08-01T06:41:57","guid":{"rendered":"http:\/\/fjala.shkoder.net\/?p=9719"},"modified":"2011-08-01T07:41:57","modified_gmt":"2011-08-01T06:41:57","slug":"borxhi-publik-qe-po-trondit-ameriken","status":"publish","type":"post","link":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/","title":{"rendered":"Borxhi publik q\u00eb po trondit Amerik\u00ebn"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright size-thumbnail wp-image-7236\" title=\"Adrian Civici\" src=\"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg\" alt=\"\" width=\"150\" \/> <strong>ADRIAN CIVICI<\/strong>, <em>01.08.2011<\/em><\/p>\n<p>Mbas shum\u00eb muajsh de batesh, frike p\u00ebr t\u00eb ardhmen dhe stabilitetin e BE-s\u00eb, borxhi publik europian, kriza greke dhe dyshimet mbi rolin e q\u00ebndrueshm\u00ebrin\u00eb e euros duket se kan\u00eb kaluar n\u00eb plan t\u00eb dyt\u00eb t\u00eb shqet\u00ebsimeve nd\u00ebrkomb\u00ebtare n\u00eb lidhje me pasojat negative n\u00eb tregjet financiare e globale q\u00eb ato mund t\u00eb shkaktojn\u00eb. Q\u00eb prej disa jav\u00ebsh, syt\u00eb e gjith\u00eb bot\u00ebs monetare e financiare jan\u00eb drejtuar nga SHBA, ku diskutohet dhe pritet t\u00eb marr\u00eb zgjidhje nj\u00eb nga rebuset m\u00eb t\u00eb v\u00ebshtira financiare jo vet\u00ebm p\u00ebr SHBA, por p\u00ebr mbar\u00eb bot\u00ebn, \u201ce ardhmja e borxhit publik n\u00eb SHBA\u201d.<\/p>\n<p>Megjith\u00ebse p\u00ebr borxhin publik amerikan ka disa dekada q\u00eb flitet me shqet\u00ebsim p\u00ebr rritjen e vazhdueshme e shpesh t\u00eb frikshme t\u00eb tij, dit\u00ebt e fundit ai p\u00ebrb\u00ebn pa dyshim lajmin e par\u00eb p\u00ebr \u00e7do gazet\u00eb e TV n\u00eb \u00e7do cep t\u00eb globit. Vendimi p\u00ebr nj\u00eb marr\u00ebveshje m\u00eb shum\u00eb se historike nd\u00ebrmjet Sht\u00ebpis\u00eb s\u00eb Bardh\u00eb dhe Kongresit, nd\u00ebrmjet demokrat\u00ebve dhe republikan\u00ebve p\u00ebr tavanin e borxhit, po pritet si tymi i bardh\u00eb n\u00eb Vatikanm q\u00eb njofton zgjedhjen e Pap\u00ebs s\u00eb ri.<\/p>\n<p>Lajmet e fundit me nj\u00eb optimiz\u00ebm t\u00eb moderuar njoftojn\u00eb p\u00ebr \u201cafrimin e pozicionit t\u00eb pal\u00ebve drejt nj\u00eb kompromisi t\u00eb af\u00ebrt\u201d. Data 2 gusht, dat\u00eb p\u00ebrtej s\u00eb cil\u00ebs n\u00eb qoft\u00eb se SHBA nuk gjen nj\u00eb zgjidhje kompromisi, mund t\u00eb detyrohet p\u00ebr her\u00eb t\u00eb par\u00eb n\u00eb historin\u00eb e saj q\u00eb t\u00eb shpall\u00eb bllokimin e pagesave dhe detyrimeve financiare. Fenomeni q\u00eb u luftua me shum\u00eb ngulm q\u00eb t\u00eb mos ndodhte n\u00eb Greqin\u00eb modeste, e cila p\u00ebrfaq\u00ebson vet\u00ebm 2% t\u00eb PBB europian, tashm\u00eb rrezikon t\u00eb prek\u00eb vendin dhe ekonomin\u00eb m\u00eb t\u00eb zhvilluar n\u00eb bot\u00eb.<\/p>\n<p>P\u00ebrball\u00eb munges\u00ebs s\u00eb deritashme t\u00eb kompromisit nd\u00ebrmjet t\u00eb zgjedhurve demokrat\u00eb e republikan\u00eb q\u00eb refuzojn\u00eb reciprokisht propozimet dhe alternativat e zgjidhjes s\u00eb nj\u00ebritjetrit, Presidenti Obama \u00ebsht\u00eb angazhuar intensivisht n\u00eb k\u00ebrkim t\u00eb nj\u00eb zgjidhjeje t\u00eb shpejt\u00eb kompromisi, q\u00eb gjithsesi ka brenda saj mjaft elemente t\u00eb luft\u00ebs politike dhe kalendarit t\u00eb zgjedhjeve legjislative e presidenciale amerikane. Ekspert\u00ebt e financave e cil\u00ebsojn\u00eb n\u00eb m\u00ebnyr\u00eb figurative k\u00ebt\u00eb situat\u00eb t\u00eb ngjashme me komedin\u00eb e famshme muzikore t\u00eb vitit 1951 \u00abDancing on the ceiling\u00bb t\u00eb Fred Astaire. Ashtu si balerin\u00ebt q\u00eb k\u00ebrcenin mbi tavan, tashm\u00eb \u00ebsht\u00eb gjith\u00eb sistemi ekonomik e financiar bot\u00ebror q\u00eb po mban frym\u00ebn n\u00eb pritje t\u00eb zgjidhjes s\u00eb problemit t\u00eb tavanit t\u00eb borxhit publik amerikan. Dollari dhe bonot e thesarit amerikan p\u00ebrb\u00ebjn\u00eb referenc\u00ebn m\u00eb t\u00eb r\u00ebnd\u00ebsishme t\u00eb tregjeve financiare dhe tregtis\u00eb bot\u00ebrore.<\/p>\n<p>K\u00ebt\u00eb radh\u00eb, ndoshta m\u00eb shum\u00eb se her\u00ebt e tjera, shprehja e famshme e John Connally, sekretarit amerikan t\u00eb thesarit e vitit 1971 se \u201cDollari \u00ebsht\u00eb monedha jon\u00eb, por problemi juaj\u201d, duket mjaft aktuale. T\u00eb gjith\u00eb duket se i kan\u00eb drejtuar syt\u00eb e vesh\u00ebt nga SHBA p\u00ebr t\u00eb kuptuar shkall\u00ebn e riskut apo perceptuar sinjale qet\u00ebsie dhe garancie. FMN, n\u00ebp\u00ebrmjet Christine Lagarde paralajm\u00ebron me shqet\u00ebsim se \u201cnj\u00eb nga pasojat m\u00eb t\u00eb r\u00ebnda t\u00eb k\u00ebsaj situate do t\u00eb ishte nj\u00eb r\u00ebnie e besimit tek dollari dhe zvog\u00eblim i rolit t\u00eb dollarit si monedh\u00eb rezerv\u00eb vlere\u201d.<\/p>\n<p>Duke e v\u00ebn\u00eb gishtin mbi plag\u00eb, FMN evidenton faktin se p\u00ebrtej shqet\u00ebsimit p\u00ebr uljen e vler\u00ebs s\u00eb dollarit amerikan p\u00ebrball\u00eb \u201cdy termometrave\u201d, si\u00e7 quhet ari dhe franga zvicerane, m\u00eb problematik paraqitet roli i tij i ardhsh\u00ebm si \u201cmonedh\u00eb rezerv\u00eb vlere\u201d p\u00ebr bankat qendrore n\u00eb mbar\u00eb bot\u00ebn, t\u00eb cilat kan\u00eb mbi 60% t\u00eb k\u00ebtyre rezervave n\u00eb dollar\u00eb, si dhe faktit se dy t\u00eb tretat e tregtis\u00eb bot\u00ebrore b\u00ebhen n\u00eb dollar\u00eb. Mjaft t\u00eb shqet\u00ebsuar e t\u00eb \u00e7uditur me politik\u00ebn amerikane duken dhe kinez\u00ebt, t\u00eb cil\u00ebt jan\u00eb zot\u00ebruesit m\u00eb t\u00eb m\u00ebdhenj n\u00eb bot\u00eb t\u00eb bonove t\u00eb thesarit t\u00eb qeveris\u00eb amerikane. Aktualisht, Pekini ka n\u00eb dor\u00eb 1160 miliard\u00eb dollar\u00eb bono thesari, nd\u00ebrkoh\u00eb q\u00eb Banka Qendrore Kineze vet\u00ebm gjat\u00eb vitit 2010 i shtoi me 620 miliard\u00eb dollar\u00eb rezervat e saj monetare.<\/p>\n<p>\u00c7do ulje e vler\u00ebs s\u00eb dollarit apo tronditje e tij do t\u00eb reflektohej menj\u00ebher\u00eb negativisht edhe n\u00eb Kin\u00eb, gj\u00eb q\u00eb ka b\u00ebr\u00eb q\u00eb Kina t\u2019i ngrej\u00eb tonet duke i k\u00ebrkuar SHBA q\u00eb t\u00eb \u201cmendoj\u00eb dhe p\u00ebr interesat e Kin\u00ebs\u201d, dhe q\u00eb ekonomia bot\u00ebrore t\u00eb mos merret peng nga interesat politik\u00eb t\u00eb republikan\u00ebve apo demokrat\u00ebve n\u00eb SHBA. Por, \u00e7far\u00eb po ndodh me borxhin publik amerikan dhe cil\u00ebt jan\u00eb skenar\u00ebt e mundsh\u00ebm t\u00eb zgjidhjes s\u00eb k\u00ebsaj nyje gordiane? Aktualisht, borxhi publik amerikan ka arritur n\u00eb shifrat 14300 miliard\u00eb dollar\u00eb ose af\u00ebrsisht 10000 miliard euro, pothuajse i barabart\u00eb me 100% t\u00eb PBB amerikan.<\/p>\n<p>Por, ekspert\u00ebt e borxhit publik e avancojn\u00eb edhe m\u00eb shum\u00eb k\u00ebt\u00eb shif\u00ebr, q\u00eb n\u00eb fakt p\u00ebrfaq\u00ebson borxhin total federal, duke shtuar 3000 miliard\u00eb dollar\u00eb borxh t\u00eb shteteve t\u00eb ndryshme, si dhe 3000 miliard\u00eb t\u00eb tjer\u00eb q\u00eb p\u00ebrb\u00ebhen nga garancit\u00eb publike p\u00ebr \u201cfinancat imobiliare\u201d. N\u00eb k\u00ebt\u00eb k\u00ebndv\u00ebshtrim, n\u00eb total borxhi publik amerikan arrin n\u00eb 140% t\u00eb PBB(!) Shif\u00ebr kjo 240% m\u00eb e lart\u00eb se tavani prej 60%, q\u00eb nga gjith\u00eb ekspert\u00ebt financiar\u00eb fiksohet si \u201cvija e kuqe q\u00eb nuk duhet kaluar\u201d. Shuma prej 14294 miliard\u00eb dollar\u00ebsh ishte fiksuar nga Kongresi Amerikan si kufiri i sip\u00ebrm i borxhit, por q\u00eb u arrit dhe u kalua q\u00eb n\u00eb jav\u00ebt e para t\u00eb muajit maj 2011.<\/p>\n<p>P\u00ebr Presidentin Obama, problemi i borxhit t\u00eb jasht\u00ebzakonsh\u00ebm t\u00eb SHBA \u00ebsht\u00eb pasoj\u00eb e politikave t\u00eb kaluara fiskale mjaft liberale. Gjith\u00e7ka duket se fillon me presidenc\u00ebn e Ronald Reagan-it, q\u00eb premtonte nj\u00eb shtet minimal, q\u00eb zvog\u00eblonte taksat, por q\u00eb rriste pareshtur shpenzimet. T\u00eb nj\u00ebjt\u00ebn linj\u00eb duket se ndoqi dhe Presidenti Xhorxh Bush, q\u00eb e \u00e7oi n\u00eb 82% borxhin publik n\u00eb raport me PBB, nd\u00ebrkoh\u00eb q\u00eb vet\u00eb Obama e shpjegon rritjen drastike t\u00eb borxhit n\u00eb mandatin e tij si \u201cnevoj\u00eb p\u00ebr t\u00eb shp\u00ebtuar Amerik\u00ebn nga nj\u00eb recesion i fort\u00eb ekonomik\u201d. Cil\u00ebt jan\u00eb skenar\u00ebt e mundsh\u00ebm q\u00eb mund t\u00eb ndodhim n\u00eb dit\u00ebt n\u00eb vazhdim?<\/p>\n<p>Skenari m\u00eb i keq dhe m\u00eb i pad\u00ebshiruar, por q\u00eb gjithsesi ka pak gjasa t\u00eb ndodh\u00eb, \u00ebsht\u00eb \u201cmosarritja e nj\u00eb marr\u00ebveshjeje nd\u00ebrmjet pal\u00ebve deri n\u00eb dat\u00ebn 2 gusht\u201d, dat\u00eb p\u00ebrtej s\u00eb cil\u00ebs Ministria e Financave dhe Thesari amerikan nuk mund t\u00eb marrin m\u00eb borxh n\u00eb tregjet financiare p\u00ebr t\u00eb realizuar shpenzimet e parashikuara dhe nj\u00ebkoh\u00ebsisht nuk mund t\u00eb paguajn\u00eb dot detyrimet e tyre ndaj kreditor\u00ebve n\u00eb data shum\u00eb t\u00eb af\u00ebrta t\u00eb maturitetit t\u00eb bonove t\u00eb thesarit dhe obligacioneve t\u00eb ndryshme. Mjafton t\u00eb p\u00ebrmendet vet\u00ebm fakti se detyrimet e k\u00ebtij tipi jan\u00eb rimbursimi i 30 miliard\u00eb USD n\u00eb 4 gusht, 27 miliard\u00eb USD t\u00eb tjer\u00eb n\u00eb 11 gusht dhe 25 USD n\u00eb 25 gusht.<\/p>\n<p>Pagat e funksionar\u00ebve federal\u00eb dhe t\u00eb gjitha pagesat e tjera federale jan\u00eb n\u00eb rrezik bllokimi. Kjo situat\u00eb e pamund\u00ebsis\u00eb s\u00eb Thesarit p\u00ebr t\u00eb respektuar angazhimet e tij, mund t\u2019i detyroje agjencit\u00eb e vler\u00ebsimit Standard &amp; Poor\u2019s, Moody\u2019s dhe Fitch ta cil\u00ebsonin SHBA n\u00eb situat\u00ebn e \u201cpamund\u00ebsis\u00eb teknike t\u00eb pagesave\u201d dhe ta ulnin vler\u00ebsimin e tyre nga AAA n\u00eb AA+, \u00e7ka do t\u00eb p\u00ebrb\u00ebnte rastin e par\u00eb n\u00eb historin\u00eb moderne t\u00eb SHBA q\u00eb \u201cborxhi m\u00eb i sigurt i bot\u00ebs me rrezik zero\u201d t\u00eb l\u00ebkundej n\u00eb garancit\u00eb e tij.<\/p>\n<p>Sipas zyr\u00ebs s\u00eb buxhetit n\u00eb Kongresin Amerikan, nj\u00eb gj\u00eb e till\u00eb mund t\u00eb shkaktonte nj\u00eb r\u00ebnie t\u00eb ndjeshme t\u00eb bursave, ngritje t\u00eb p\u00ebrqindjeve t\u00eb interesit p\u00ebr kredit\u00eb dhe transaksioneve financiare, nj\u00eb ulje t\u00eb m\u00ebtejshme t\u00eb vler\u00ebs s\u00eb dollarit n\u00eb tregjet valutore nd\u00ebrkomb\u00ebtare, si dhe \u00e7rregullime t\u00eb sistemit t\u00eb pagesave dhe tregjeve t\u00eb kredis\u00eb. Duke pasur parasysh r\u00ebnd\u00ebsin\u00eb e ekonomis\u00eb amerikane n\u00eb tregje dhe tregtin\u00eb bot\u00ebrore, si dhe nd\u00ebrthurjen globale t\u00eb tregjeve financiare, kriza mund t\u00eb kishte pasoja t\u00eb r\u00ebnda n\u00eb shum\u00eb vende t\u00eb tjera t\u00eb bot\u00ebs.<\/p>\n<p>Skenari i dyt\u00eb, i cil\u00ebsuar si \u201cskenari gri\u201d, n\u00ebnkupton arritjen e nj\u00eb marr\u00ebveshjeje nd\u00ebrmjet republikan\u00ebve dhe demokrat\u00ebve, vet\u00ebm n\u00eb lidhje me tavanin e borxhit. Natyrisht q\u00eb kjo nuk do t\u00eb ishte e mjaftueshme p\u00ebr t\u2019i shp\u00ebtuar vler\u00ebsimit negativ t\u00eb agjencive vler\u00ebsuese, q\u00eb gjithsesi do ta shtonin presionin p\u00ebr t\u00eb ulur vler\u00ebsimin e cil\u00ebsis\u00eb s\u00eb borxhit amerikan nga AAA n\u00eb AA+. Kjo do b\u00ebnte q\u00eb kostoja e borxhit amerikan t\u00eb shtohej me 130 miliard\u00eb USD n\u00eb 10 vitet e ardhshme, por nga ana tjet\u00ebr do ndikonte pozitivisht p\u00ebr eliminimin e panikut n\u00eb tregjet financiare.<\/p>\n<p>Zot\u00ebruesit e titujve t\u00eb borxhit amerikan do ishin m\u00eb t\u00eb qet\u00eb p\u00ebr t\u00eb pritur pages\u00ebn normale dhe maturitetin e bonove t\u00eb thesarit q\u00eb zot\u00ebrojn\u00eb. Presidenti Obama ka paralajm\u00ebruar se konflikti politik mund t\u00eb provokoj\u00eb nj\u00eb ulje t\u00eb vler\u00ebsimit ton\u00eb AAA, \u00e7ka na leht\u00ebson financime me norma interesi t\u00eb favorshme. N\u00ebse vendi humbet k\u00ebt\u00eb vler\u00ebsim, kjo do t\u00eb thot\u00eb se \u201cvendi nuk ka nj\u00eb sistem politik t\u00eb vler\u00ebsuesh\u00ebm AAA ose n\u00eb nivelin e borxhit t\u00eb tij\u201d.<\/p>\n<p>Skenari i tret\u00eb, q\u00eb konsiderohet si m\u00eb i miri dhe m\u00eb shpres\u00ebdh\u00ebn\u00ebsi, n\u00ebnkupton nj\u00eb kompromis t\u00eb gjer\u00eb q\u00eb shtrihet nga aprovimi i nj\u00eb tavani t\u00eb ri p\u00ebr borxhin publik, deri tek marr\u00ebveshja p\u00ebr reduktimin e deficitit buxhetor amerikan me 4000 miliard USD n\u00eb vitet e ardhshme. N\u00eb k\u00ebt\u00eb rast, agjencit\u00eb e vler\u00ebsimit do ishin t\u00eb qeta p\u00ebr aft\u00ebsin\u00eb paguese t\u00eb borxhit nga SHBA dhe do ta mbanin t\u00eb pandryshuar nivelin AAA t\u00eb vler\u00ebsimit, duke leht\u00ebsuar \u00e7do lloj marrje borxhi apo garantuar kreditor\u00ebt e borxhit amerikan p\u00ebr sigurin\u00eb absolute t\u00eb tij.<\/p>\n<p>Por, ekspert\u00ebt e financave publike n\u00ebnvizojn\u00eb faktin se reduktimi me 4000 miliard\u00eb USD i deficitit buxhetor n\u00eb SHBA do t\u2019i kushtonte mjaft shtrenjt\u00eb ekonomis\u00eb amerikane. Sipas nj\u00eb studimi t\u00eb FMN, SHBA do t\u00eb ishte e detyruar q\u00eb t\u2019i n\u00ebnshtrohej nj\u00eb rigoroziteti buxhetor akoma dhe m\u00eb t\u00eb ashp\u00ebr se rasti grek, irlandez apo portugez, gj\u00eb q\u00eb nuk ka ndodhur asnj\u00ebher\u00eb n\u00eb ekonomin\u00eb amerikane. Data m\u00eb e af\u00ebrt p\u00ebr ta ulur borxhin publik amerikan n\u00eb nivelin 60% t\u00eb PBB duket viti 2030.<\/p>\n<p>Nd\u00ebrkoh\u00eb, shum\u00eb ekonomist\u00eb dhe analist\u00eb financiar\u00eb mendojn\u00eb se problemi i v\u00ebrtet\u00eb nuk q\u00ebndron tek tavani i borxhit apo deficiti buxhetor, por tek kapaciteti i ekonomis\u00eb amerikane p\u00ebr t\u00eb garantuar rritje t\u00eb lart\u00eb e t\u00eb q\u00ebndrueshme ekonomike, p\u00ebr t\u00eb rritur nivelin e pun\u00ebsimit. Stabiliteti dhe dinamika e ekonomis\u00eb amerikane kusht\u00ebzon dhe prek gjith\u00eb ekonomin\u00eb bot\u00ebrore, duke i dh\u00ebn\u00eb t\u00eb drejt\u00eb konstatimit se \u201ckur Amerika ka ftoht\u00eb, teshtin gjith\u00eb ekonomia bot\u00ebrore\u201d. Sh\u00ebndeti i saj u intereson t\u00eb gjith\u00ebve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ADRIAN CIVICI, 01.08.2011 Mbas shum\u00eb muajsh de batesh, frike p\u00ebr t\u00eb ardhmen dhe stabilitetin e BE-s\u00eb, borxhi publik europian, kriza greke dhe dyshimet mbi rolin e q\u00ebndrueshm\u00ebrin\u00eb e euros duket se kan\u00eb kaluar n\u00eb plan t\u00eb dyt\u00eb t\u00eb shqet\u00ebsimeve nd\u00ebrkomb\u00ebtare n\u00eb lidhje me pasojat negative n\u00eb tregjet financiare e globale q\u00eb ato mund t\u00eb shkaktojn\u00eb. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-9719","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-artikuj"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Borxhi publik q\u00eb po trondit Amerik\u00ebn - FjALA e LIR\u00cb - Arkivi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borxhi publik q\u00eb po trondit Amerik\u00ebn - FjALA e LIR\u00cb - Arkivi\" \/>\n<meta property=\"og:description\" content=\"ADRIAN CIVICI, 01.08.2011 Mbas shum\u00eb muajsh de batesh, frike p\u00ebr t\u00eb ardhmen dhe stabilitetin e BE-s\u00eb, borxhi publik europian, kriza greke dhe dyshimet mbi rolin e q\u00ebndrueshm\u00ebrin\u00eb e euros duket se kan\u00eb kaluar n\u00eb plan t\u00eb dyt\u00eb t\u00eb shqet\u00ebsimeve nd\u00ebrkomb\u00ebtare n\u00eb lidhje me pasojat negative n\u00eb tregjet financiare e globale q\u00eb ato mund t\u00eb shkaktojn\u00eb. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/\" \/>\n<meta property=\"og:site_name\" content=\"FjALA e LIR\u00cb - Arkivi\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-01T06:41:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#\\\/schema\\\/person\\\/9fb2acd4356288cf78f47dc592b7b4a3\"},\"headline\":\"Borxhi publik q\u00eb po trondit Amerik\u00ebn\",\"datePublished\":\"2011-08-01T06:41:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/\"},\"wordCount\":1854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.shkoder.net\\\/images\\\/fjala\\\/adrian_civici.jpg\",\"articleSection\":[\"Artikuj\"],\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/\",\"url\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/\",\"name\":\"Borxhi publik q\u00eb po trondit Amerik\u00ebn - FjALA e LIR\u00cb - Arkivi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.shkoder.net\\\/images\\\/fjala\\\/adrian_civici.jpg\",\"datePublished\":\"2011-08-01T06:41:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.shkoder.net\\\/images\\\/fjala\\\/adrian_civici.jpg\",\"contentUrl\":\"http:\\\/\\\/www.shkoder.net\\\/images\\\/fjala\\\/adrian_civici.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/borxhi-publik-qe-po-trondit-ameriken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Borxhi publik q\u00eb po trondit Amerik\u00ebn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#website\",\"url\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/\",\"name\":\"FjALA e LIR\u00cb - Arkivi\",\"description\":\"Arkivi 2009-2015\",\"publisher\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#organization\",\"name\":\"FjALA e LIR\u00cb - Arkivi\",\"url\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"FjALA e LIR\u00cb - Arkivi\"},\"image\":{\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/#\\\/schema\\\/person\\\/9fb2acd4356288cf78f47dc592b7b4a3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/arben_cokaj-120x150.jpg\",\"url\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/arben_cokaj-120x150.jpg\",\"contentUrl\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/arben_cokaj-120x150.jpg\",\"caption\":\"admin\"},\"description\":\"Admin, Fjala e Lir\u00eb\",\"sameAs\":[\"https:\\\/\\\/fjala.info\\\/\"],\"url\":\"https:\\\/\\\/fjala.info\\\/2009-2015\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borxhi publik q\u00eb po trondit Amerik\u00ebn - FjALA e LIR\u00cb - Arkivi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/","og_locale":"sq_AL","og_type":"article","og_title":"Borxhi publik q\u00eb po trondit Amerik\u00ebn - FjALA e LIR\u00cb - Arkivi","og_description":"ADRIAN CIVICI, 01.08.2011 Mbas shum\u00eb muajsh de batesh, frike p\u00ebr t\u00eb ardhmen dhe stabilitetin e BE-s\u00eb, borxhi publik europian, kriza greke dhe dyshimet mbi rolin e q\u00ebndrueshm\u00ebrin\u00eb e euros duket se kan\u00eb kaluar n\u00eb plan t\u00eb dyt\u00eb t\u00eb shqet\u00ebsimeve nd\u00ebrkomb\u00ebtare n\u00eb lidhje me pasojat negative n\u00eb tregjet financiare e globale q\u00eb ato mund t\u00eb shkaktojn\u00eb. [&hellip;]","og_url":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/","og_site_name":"FjALA e LIR\u00cb - Arkivi","article_published_time":"2011-08-01T06:41:57+00:00","og_image":[{"url":"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#article","isPartOf":{"@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/"},"author":{"name":"admin","@id":"https:\/\/fjala.info\/2009-2015\/#\/schema\/person\/9fb2acd4356288cf78f47dc592b7b4a3"},"headline":"Borxhi publik q\u00eb po trondit Amerik\u00ebn","datePublished":"2011-08-01T06:41:57+00:00","mainEntityOfPage":{"@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/"},"wordCount":1854,"commentCount":0,"publisher":{"@id":"https:\/\/fjala.info\/2009-2015\/#organization"},"image":{"@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#primaryimage"},"thumbnailUrl":"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg","articleSection":["Artikuj"],"inLanguage":"sq-AL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/","url":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/","name":"Borxhi publik q\u00eb po trondit Amerik\u00ebn - FjALA e LIR\u00cb - Arkivi","isPartOf":{"@id":"https:\/\/fjala.info\/2009-2015\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#primaryimage"},"image":{"@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#primaryimage"},"thumbnailUrl":"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg","datePublished":"2011-08-01T06:41:57+00:00","breadcrumb":{"@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#primaryimage","url":"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg","contentUrl":"http:\/\/www.shkoder.net\/images\/fjala\/adrian_civici.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fjala.info\/2009-2015\/borxhi-publik-qe-po-trondit-ameriken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fjala.info\/2009-2015\/"},{"@type":"ListItem","position":2,"name":"Borxhi publik q\u00eb po trondit Amerik\u00ebn"}]},{"@type":"WebSite","@id":"https:\/\/fjala.info\/2009-2015\/#website","url":"https:\/\/fjala.info\/2009-2015\/","name":"FjALA e LIR\u00cb - Arkivi","description":"Arkivi 2009-2015","publisher":{"@id":"https:\/\/fjala.info\/2009-2015\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fjala.info\/2009-2015\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/fjala.info\/2009-2015\/#organization","name":"FjALA e LIR\u00cb - Arkivi","url":"https:\/\/fjala.info\/2009-2015\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/fjala.info\/2009-2015\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"FjALA e LIR\u00cb - Arkivi"},"image":{"@id":"https:\/\/fjala.info\/2009-2015\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fjala.info\/2009-2015\/#\/schema\/person\/9fb2acd4356288cf78f47dc592b7b4a3","name":"admin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/fjala.info\/2009-2015\/wp-content\/uploads\/2012\/02\/arben_cokaj-120x150.jpg","url":"https:\/\/fjala.info\/2009-2015\/wp-content\/uploads\/2012\/02\/arben_cokaj-120x150.jpg","contentUrl":"https:\/\/fjala.info\/2009-2015\/wp-content\/uploads\/2012\/02\/arben_cokaj-120x150.jpg","caption":"admin"},"description":"Admin, Fjala e Lir\u00eb","sameAs":["https:\/\/fjala.info\/"],"url":"https:\/\/fjala.info\/2009-2015\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/posts\/9719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/comments?post=9719"}],"version-history":[{"count":0,"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/posts\/9719\/revisions"}],"wp:attachment":[{"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/media?parent=9719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/categories?post=9719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fjala.info\/2009-2015\/wp-json\/wp\/v2\/tags?post=9719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}